{"id":7828,"date":"2024-01-17T08:47:29","date_gmt":"2024-01-17T11:47:29","guid":{"rendered":"https:\/\/ocoerente.com.br\/se\/?p=7828"},"modified":"2024-01-17T08:47:30","modified_gmt":"2024-01-17T11:47:30","slug":"governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/","title":{"rendered":"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher"},"content":{"rendered":"\n<p><em>Programa garante seis parcelas, no valor de R$ 500,00 cada, para mulheres socialmente vulner\u00e1veis em situa\u00e7\u00e3o de pobreza ou extrema pobreza<\/em><\/p>\n\n\n\n<p>Est\u00e1 aberta at\u00e9 a pr\u00f3xima segunda-feira, 22, mais uma fase de inscri\u00e7\u00f5es do Cart\u00e3o Mais Inclus\u00e3o \u2013 CMais Mulher. O programa faz parte da pol\u00edtica de prote\u00e7\u00e3o \u00e0s mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica desenvolvida pelo Governo de Sergipe, por meio da Secretaria de Pol\u00edticas para as Mulheres (SPM)&nbsp;e j\u00e1 alcan\u00e7ou mais de 600 benefici\u00e1rias.<br>&nbsp;<br>As interessadas devem buscar os equipamentos sociais (Creas, Cram, Casa da Mulher) dos munic\u00edpios para saberem se t\u00eam direito ao benef\u00edcio e realizar a solicita\u00e7\u00e3o. \u201cEsses equipamentos est\u00e3o aptos para esclarecer poss\u00edveis d\u00favidas e realizar o preenchimento do formul\u00e1rio de inscri\u00e7\u00e3o, al\u00e9m de anexar devidamente os documentos solicitados\u201d, destaca a secret\u00e1ria Danielle Garcia.<br>&nbsp;<br>O programa garante seis parcelas, no valor de R$ 500,00 cada, para mulheres socialmente vulner\u00e1veis, em situa\u00e7\u00e3o de pobreza ou extrema pobreza, que sejam v\u00edtimas de viol\u00eancia dom\u00e9stica e familiar e estejam inseridas em medidas de prote\u00e7\u00e3o vigentes e inscritas no Cad\u00danico &#8211; linha da pobreza.<br>&nbsp;<br>Al\u00e9m disso, a iniciativa do Governo de Sergipe representa um avan\u00e7o nas a\u00e7\u00f5es de prote\u00e7\u00e3o \u00e0 mulher no estado, que \u00e9 executada em rede por diversos \u00f3rg\u00e3os, e visa atender ao disposto na Lei Maria da Penha, quanto \u00e0 cria\u00e7\u00e3o de mecanismos para coibir a viol\u00eancia dom\u00e9stica. A partir do benef\u00edcio financeiro, a lei busca a garantia de subsist\u00eancia m\u00ednima dessa mulher para sair do ambiente do agressor.<\/p>\n\n\n\n<p>De acordo com a secret\u00e1ria Danielle Garcia, esta nova fase do CMais Mulher refor\u00e7a o compromisso do Governo do Estado de implementar pol\u00edticas p\u00fablicas de prote\u00e7\u00e3o e combate \u00e0 viol\u00eancia contra a mulher. \u201cJ\u00e1 temos mulheres recebendo o benef\u00edcio e agora estamos com mais vagas dispon\u00edveis. \u00c9 importante ressaltar que, al\u00e9m da transfer\u00eancia de renda, acolhemos essa mulher psicossocialmente, disponibilizando ainda capacita\u00e7\u00e3o e buscando incluir no mercado de trabalho\u201d, salienta.<\/p>\n\n\n\n<p>se.gov.br<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programa garante seis parcelas, no valor de R$ 500,00 cada, para mulheres socialmente vulner\u00e1veis em situa\u00e7\u00e3o de pobreza ou extrema pobreza Est\u00e1 aberta at\u00e9 a pr\u00f3xima segunda-feira, 22, mais uma fase de inscri\u00e7\u00f5es do Cart\u00e3o Mais Inclus\u00e3o \u2013 CMais Mulher. O programa faz parte da pol\u00edtica de prote\u00e7\u00e3o \u00e0s mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica desenvolvida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7829,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,43],"tags":[],"class_list":["post-7828","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-sergipe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher - O Coerente\" \/>\n<meta property=\"og:description\" content=\"Programa garante seis parcelas, no valor de R$ 500,00 cada, para mulheres socialmente vulner\u00e1veis em situa\u00e7\u00e3o de pobreza ou extrema pobreza Est\u00e1 aberta at\u00e9 a pr\u00f3xima segunda-feira, 22, mais uma fase de inscri\u00e7\u00f5es do Cart\u00e3o Mais Inclus\u00e3o \u2013 CMais Mulher. O programa faz parte da pol\u00edtica de prote\u00e7\u00e3o \u00e0s mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica desenvolvida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-17T11:47:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-17T11:47:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/01\/cmamaismulher.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"headline\":\"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher\",\"datePublished\":\"2024-01-17T11:47:29+00:00\",\"dateModified\":\"2024-01-17T11:47:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/\"},\"wordCount\":378,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cmamaismulher.jpg\",\"articleSection\":[\"Destaques\",\"Sergipe\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/\",\"name\":\"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cmamaismulher.jpg\",\"datePublished\":\"2024-01-17T11:47:29+00:00\",\"dateModified\":\"2024-01-17T11:47:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cmamaismulher.jpg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cmamaismulher.jpg\",\"width\":1100,\"height\":610,\"caption\":\"Foto: Seasc\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/01\\\/17\\\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"},\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/vasticlsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher - O Coerente","og_description":"Programa garante seis parcelas, no valor de R$ 500,00 cada, para mulheres socialmente vulner\u00e1veis em situa\u00e7\u00e3o de pobreza ou extrema pobreza Est\u00e1 aberta at\u00e9 a pr\u00f3xima segunda-feira, 22, mais uma fase de inscri\u00e7\u00f5es do Cart\u00e3o Mais Inclus\u00e3o \u2013 CMais Mulher. O programa faz parte da pol\u00edtica de prote\u00e7\u00e3o \u00e0s mulheres v\u00edtimas de viol\u00eancia dom\u00e9stica desenvolvida [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/","og_site_name":"O Coerente","article_published_time":"2024-01-17T11:47:29+00:00","article_modified_time":"2024-01-17T11:47:30+00:00","og_image":[{"width":1100,"height":610,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/01\/cmamaismulher.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"headline":"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher","datePublished":"2024-01-17T11:47:29+00:00","dateModified":"2024-01-17T11:47:30+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/"},"wordCount":378,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/01\/cmamaismulher.jpg","articleSection":["Destaques","Sergipe"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/","url":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/","name":"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/01\/cmamaismulher.jpg","datePublished":"2024-01-17T11:47:29+00:00","dateModified":"2024-01-17T11:47:30+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/01\/cmamaismulher.jpg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/01\/cmamaismulher.jpg","width":1100,"height":610,"caption":"Foto: Seasc"},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2024\/01\/17\/governo-de-sergipe-inicia-nova-fase-de-inscricoes-para-o-programa-cmais-mulher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"Governo de Sergipe inicia nova fase de inscri\u00e7\u00f5es para o programa CMais Mulher"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"},"url":"https:\/\/ocoerente.com.br\/se\/author\/vasticlsales\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/7828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=7828"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/7828\/revisions"}],"predecessor-version":[{"id":7830,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/7828\/revisions\/7830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/7829"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=7828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=7828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=7828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}