{"id":668,"date":"2020-03-29T01:00:16","date_gmt":"2020-03-29T04:00:16","guid":{"rendered":"http:\/\/ocoerente.com.br\/se\/?p=668"},"modified":"2020-03-29T01:00:16","modified_gmt":"2020-03-29T04:00:16","slug":"prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/","title":{"rendered":"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar"},"content":{"rendered":"<p>A Prefeitura de Aracaju definiu, na manh\u00e3 desta sexta-feira, 27, como ser\u00e1 feita a distribui\u00e7\u00e3o dos kits de alimenta\u00e7\u00e3o escolar para as crian\u00e7as matriculadas na rede municipal de ensino. A medida foi uma das determina\u00e7\u00f5es estabelecidas pela administra\u00e7\u00e3o municipal para o enfrentamento ao coronav\u00edrus na capital sergipana, e tem como finalidade garantir um refor\u00e7o alimentar aos alunos, durante o per\u00edodo de suspens\u00e3o das aulas, por conta do v\u00edrus. Em entrevista \u00e0 imprensa, Edvaldo confirmou que a entrega dos kits se iniciar\u00e1 na segunda-feira, 30, das 8h \u00e0s 17h,\u00a0 pelas \u00e1reas mais vulner\u00e1veis da cidade, no caso os bairros Santa Maria e 17 de Mar\u00e7o. As For\u00e7as Armadas atuar\u00e3o junto \u00e0 Prefeitura na distribui\u00e7\u00e3o.<\/p>\n<p>\u201cTenho certeza de que essa a\u00e7\u00e3o ser\u00e1 um sucesso e que os kits ser\u00e3o muito bem distribu\u00eddos, chegando na hora certa para os nossos alunos. Todas os 32 mil alunos, matriculados na rede municipal, ser\u00e3o contemplados. O que quer dizer que n\u00e3o ser\u00e1 por fam\u00edlia, mas por aluno, ent\u00e3o se houver tr\u00eas crian\u00e7as na mesma casa que estudam na rede municipal, as tr\u00eas receber\u00e3o os kits. Sabemos que \u00e9 muito importante garantir a alimenta\u00e7\u00e3o dos nossos alunos que est\u00e3o na faixa de idade de 0 a 14 anos. Eles precisam desse complemento alimentar e \u00e9 por isso que adotamos essa medida. Vamos come\u00e7ar pelas \u00e1reas mais vulner\u00e1veis da cidade, pelos bairros Santa Maria e 17 de Mar\u00e7o, e a distribui\u00e7\u00e3o ser\u00e1 feita no hor\u00e1rio em que o aluno estuda\u201d, informou o prefeito.<\/p>\n<p>Edvaldo ressaltou que a presen\u00e7a do Ex\u00e9rcito e da Marinha \u201cdar\u00e1 seguran\u00e7a\u201d \u00e0 popula\u00e7\u00e3o. \u201cN\u00e3o \u00e9 uma opera\u00e7\u00e3o f\u00e1cil. Por isso fizemos o convite e ficamos muito felizes de termos sido atendidos. O apoio da Marinha e do Ex\u00e9rcito nos dar\u00e1 a garantia de que todas as crian\u00e7as das 74 escolas ser\u00e3o prontamente atendidas e que os meninos e meninas ter\u00e3o acesso, aos kits, da maneira correta\u201d, salientou.<\/p>\n<p>A secret\u00e1ria da Educa\u00e7\u00e3o, Cec\u00edlia Leite, explicou que o cronograma de distribui\u00e7\u00e3o foi elaborado com base no Observat\u00f3rio Social do munic\u00edpio. \u201cUsamos este instrumento muito importante porque ele identifica as \u00e1reas mais vulner\u00e1veis da cidade. Por isso come\u00e7aremos pelos bairros 17 de Mar\u00e7o e Santa Maria. De l\u00e1, seguiremos para outras regi\u00f5es, cumprindo com o nosso cronograma. Mas \u00e9 importante refor\u00e7ar que cada crian\u00e7a receber\u00e1 um kit, ent\u00e3o a fam\u00edlia que possui duas, tr\u00eas crian\u00e7as matriculadas em nossa rede, vai ter direito a dois, tr\u00eas kits. Est\u00e1 assegurado para os 32 mil alunos matriculados na rede municipal de Aracaju\u201d, detalhou.<\/p>\n<p>O comandante do 28\u00ba Batalh\u00e3o de Ca\u00e7adores, tenente coronel Marco Aur\u00e9lio Magalh\u00e3es elogiou a a\u00e7\u00e3o da Prefeitura e enfatizou que a miss\u00e3o das For\u00e7as Armadas \u00e9 cooperar. \u201cA Prefeitura realizou o planejamento para distribui\u00e7\u00e3o dos kits de alimenta\u00e7\u00e3o nas escolas e nos convidou para apoiar nessa entrega, garantindo que o alimento chegue \u00e0s crian\u00e7as. Ent\u00e3o a presen\u00e7a dos militares \u00e9 para dar credibilidade a essa entrega, de forma que a popula\u00e7\u00e3o veja que h\u00e1 organiza\u00e7\u00e3o e empenho para entregar os alimentos. Estaremos em todas as escolas com uma equipe, apoiando a a\u00e7\u00e3o e colaborando. Vamos garantir que tudo ocorra com tranquilidade e seguran\u00e7a\u201d, ratificou.<\/p>\n<p>De mesmo modo,\u00a0 o capit\u00e3o de Portos, Guilherme Conti Pad\u00e3o, disse que a Marinha \u201crecebe a miss\u00e3o com grande satisfa\u00e7\u00e3o\u201d. \u201cMantemos uma rela\u00e7\u00e3o muito boa com a Prefeitura e com certeza realizaremos um grande trabalho em conjunto. Foram estabelecidas \u00e1reas de distribui\u00e7\u00e3o e estaremos presentes em duas escolas com nossas equipes, garantindo a seguran\u00e7a e conforto das pessoas. A solicita\u00e7\u00e3o da Prefeitura foi justamente essa, que a seguran\u00e7a seja mantida. Ent\u00e3o faremos com que as pessoas se sintam seguras e que a ordem seja mantida com as melhores condi\u00e7\u00f5es poss\u00edveis\u201d, reiterou.<\/p>\n<p><strong>Distribui\u00e7\u00e3o<\/strong><\/p>\n<p>A distribui\u00e7\u00e3o ter\u00e1 in\u00edcio no dia 30 de mar\u00e7o, quando ser\u00e3o atendidas todas as escolas pertencentes \u00e0 7\u00aa Regi\u00e3o (Santa Maria e 17 de Mar\u00e7o), e se estender\u00e1 at\u00e9 o dia 8 de abril \u2013 a cada dia, uma Regi\u00e3o Estudantil ser\u00e1 atendida pela a\u00e7\u00e3o que contemplar\u00e1 todos os alunos. Para que a a\u00e7\u00e3o seja colocada em pr\u00e1tica, a Educa\u00e7\u00e3o contar\u00e1 com o apoio dos servidores lotados na secretaria, gestores escolares e prestadores de servi\u00e7os das empresas terceirizadas. Todos estar\u00e3o com EPI, conforme preconizam protocolos de controle da transmiss\u00e3o do coronav\u00edrus. Para garantir a seguran\u00e7a de todos, ser\u00e1 respeitado o distanciamento entre os indiv\u00edduos e a cada troca de turma, o ambiente ser\u00e1 higienizado.<\/p>\n<p>Para as crian\u00e7as matriculadas em creches, ser\u00e3o entregues kits contendo itens como leite, cereal, \u00f3leo de soja, bebida l\u00e1ctea, leite de coco, a\u00e7\u00facar, arroz, achocolatado, biscoito, feij\u00e3o, floco de milho, molho de tomate, macarr\u00e3o,\u00a0 milho de canjica, prote\u00ednas, al\u00e9m de um kit horti. No caso dos alunos matriculados no ensino fundamental, os kits v\u00e3o conter a\u00e7\u00facar, arroz, feij\u00e3o, p\u00e3o, broa de milho, floc\u00e3o de milho, leite, macarr\u00e3o, molho de tomate, prote\u00edna e kit horti.<\/p>\n<p>O Ex\u00e9rcito Brasileiro e a Capitania dos Portos ser\u00e3o\u00a0 parceiros da Prefeitura nesta a\u00e7\u00e3o, principalmente para garantia da ordem e do cumprimento do Decreto Municipal, no que tange a proibi\u00e7\u00e3o de aglomera\u00e7\u00e3o nos espa\u00e7os p\u00fablicos. Para evitar aglomera\u00e7\u00f5es, os atendimentos ser\u00e3o feitos por turmas, respeitando os turnos de estudo dos alunos e observando o limite m\u00e1ximo de 20 pessoas, por ambiente. A entrega ter\u00e1 in\u00edcio \u00e0s 8h, para o turno da manh\u00e3, e \u00e0s 13h para o turno da tarde.<\/p>\n<p>Para recebimento do kit, o pai ou respons\u00e1vel dever\u00e1 comparecer \u00e0 escola, hor\u00e1rio de atendimento determinado para o seu filho, munido de documento de identidade e documento de identifica\u00e7\u00e3o do aluno, com foto.<\/p>\n<p><strong>Cronograma<\/strong><\/p>\n<p>No dia 30 de mar\u00e7o ser\u00e3o entregues os kits nos bairros Santa Maria e 17 de Mar\u00e7o, das seguintes escolas: Emef Jos\u00e9 Souza de Jesus; Emei Doutor Jos\u00e9 Calumby Filho; Emef Professor Laonte Gama da Silva; Emei Irene Rom\u00e3o de Brito; Emef Papa Jo\u00e3o Paulo II (e anexo); Emef Professor Diomedes Santos Silva, Emei Professor Jo\u00e3o Batista \u201cDouglas\u201d de Souza.<\/p>\n<p>No dia 31 de mar\u00e7o ser\u00e3o contemplados os bairros Aeroporto, Farol\u00e2ndia e Zona de Expans\u00e3o. J\u00e1 no dia 1\u00ba de abril as entregas acontecem nos bairros Bugio, Lamar\u00e3o, Santos Dumont e Soledade. No dia 2 de abril ser\u00e1 a vez dos bairros Am\u00e9rica, Capucho Novo, Para\u00edso, Olaria\u00a0 e S\u00e3o Carlos e no dia 3 de abril nos bairros 18 do Forte, Cidade Nova, Jap\u00e3ozinho, Palestina e Porto Dantas.\u00a0 J\u00e1 no dia 6 de abril ser\u00e1 a vez dos bairros Centro, Industrial, Jabotiana, Ponto Novo\u00a0 e Santo Ant\u00f4nio e no dia 7 de abril nos bairros Get\u00falio Vargas, Jos\u00e9 Conrado de Ara\u00fajo e Siqueira Campos. A distribui\u00e7\u00e3o finaliza no dia 8 de abril, nos bairros Atalaia, Coroa do Meio, In\u00e1cio Barbosa, Luzia e S\u00e3o Conrado.<\/p>\n<p>Para mais esclarecimentos, a Educa\u00e7\u00e3o disponibiliza canais de comunica\u00e7\u00e3o. Os telefones s\u00e3o: 3179-1538 \/ 3179-1574 \/ 98106-2969 (whatsapp).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Aracaju definiu, na manh\u00e3 desta sexta-feira, 27, como ser\u00e1 feita a distribui\u00e7\u00e3o dos kits de alimenta\u00e7\u00e3o escolar para as crian\u00e7as matriculadas na rede municipal de ensino. A medida foi uma das determina\u00e7\u00f5es estabelecidas pela administra\u00e7\u00e3o municipal para o enfrentamento ao coronav\u00edrus na capital sergipana, e tem como finalidade garantir um refor\u00e7o alimentar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,1],"tags":[],"class_list":["post-668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar - O Coerente\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Aracaju definiu, na manh\u00e3 desta sexta-feira, 27, como ser\u00e1 feita a distribui\u00e7\u00e3o dos kits de alimenta\u00e7\u00e3o escolar para as crian\u00e7as matriculadas na rede municipal de ensino. A medida foi uma das determina\u00e7\u00f5es estabelecidas pela administra\u00e7\u00e3o municipal para o enfrentamento ao coronav\u00edrus na capital sergipana, e tem como finalidade garantir um refor\u00e7o alimentar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-29T04:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/03\/alm_94951.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2418\" \/>\n\t<meta property=\"og:image:height\" content=\"1903\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"headline\":\"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar\",\"datePublished\":\"2020-03-29T04:00:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/\"},\"wordCount\":1249,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/alm_94951.jpg\",\"articleSection\":[\"Destaques\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/\",\"name\":\"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/alm_94951.jpg\",\"datePublished\":\"2020-03-29T04:00:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/alm_94951.jpg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/alm_94951.jpg\",\"width\":2418,\"height\":1903},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/03\\\/29\\\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"},\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/vasticlsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar - O Coerente","og_description":"A Prefeitura de Aracaju definiu, na manh\u00e3 desta sexta-feira, 27, como ser\u00e1 feita a distribui\u00e7\u00e3o dos kits de alimenta\u00e7\u00e3o escolar para as crian\u00e7as matriculadas na rede municipal de ensino. A medida foi uma das determina\u00e7\u00f5es estabelecidas pela administra\u00e7\u00e3o municipal para o enfrentamento ao coronav\u00edrus na capital sergipana, e tem como finalidade garantir um refor\u00e7o alimentar [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/","og_site_name":"O Coerente","article_published_time":"2020-03-29T04:00:16+00:00","og_image":[{"width":2418,"height":1903,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/03\/alm_94951.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"headline":"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar","datePublished":"2020-03-29T04:00:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/"},"wordCount":1249,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/03\/alm_94951.jpg","articleSection":["Destaques"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/","url":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/","name":"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/03\/alm_94951.jpg","datePublished":"2020-03-29T04:00:16+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/03\/alm_94951.jpg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/03\/alm_94951.jpg","width":2418,"height":1903},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2020\/03\/29\/prefeitura-iniciara-pelo-santa-maria-e-17-de-marco-entrega-de-kits-de-alimentacao-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"Prefeitura iniciar\u00e1 pelo Santa Maria e 17 de Mar\u00e7o entrega de kits de alimenta\u00e7\u00e3o escolar"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"},"url":"https:\/\/ocoerente.com.br\/se\/author\/vasticlsales\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=668"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/668\/revisions"}],"predecessor-version":[{"id":670,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/668\/revisions\/670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/669"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}