{"id":19477,"date":"2026-05-12T14:24:09","date_gmt":"2026-05-12T17:24:09","guid":{"rendered":"https:\/\/ocoerente.com.br\/se\/?p=19477"},"modified":"2026-05-12T14:24:13","modified_gmt":"2026-05-12T17:24:13","slug":"ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/","title":{"rendered":"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses"},"content":{"rendered":"\n<p>A combina\u00e7\u00e3o entre f\u00e9rias escolares, festas juninas e a Copa do Mundo deve aquecer o setor de turismo nos pr\u00f3ximos meses, aumentando o interesse de sergipanos por viagens dentro e fora do pa\u00eds, conforme explica a especialista Carol Asencio, agente de viagens. O per\u00edodo, considerado uma das fases mais movimentadas do ano, tende a concentrar ainda mais a demanda por destinos tur\u00edsticos.<\/p>\n\n\n\n<p>\u201cMuita gente acaba se dando conta das f\u00e9rias em cima da hora e encontra menos op\u00e7\u00f5es ou valores mais altos. Este ano tem um calend\u00e1rio muito forte, com S\u00e3o Jo\u00e3o e Copa do Mundo, ent\u00e3o quem se antecipa consegue aproveitar melhor e com mais tranquilidade\u201d, afirma. \u201cOs hot\u00e9is, tanto no Brasil quanto no exterior, costumam preparar programa\u00e7\u00f5es especiais, com tel\u00f5es e eventos para acompanhar os jogos. Isso cria um clima diferente e muito divertido para quem est\u00e1 viajando nesse per\u00edodo\u201d, adiciona a especialista.<\/p>\n\n\n\n<p>Com isso, cresce tamb\u00e9m a import\u00e2ncia do planejamento. A proximidade das datas costuma impactar diretamente nos pre\u00e7os e na disponibilidade, especialmente para quem deixa a organiza\u00e7\u00e3o para a \u00faltima hora. A expectativa \u00e9 de aumento na procura nas pr\u00f3ximas semanas, especialmente entre fam\u00edlias e grupos que desejam unir descanso, lazer e entretenimento em um dos per\u00edodos mais movimentados do ano.<\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre viagens durante o per\u00edodo de meio do ano, busque @befly.aracaju no Instagram ou visite uma das lojas f\u00edsicas localizadas nos bairros 13 de Julho e Jardins.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A combina\u00e7\u00e3o entre f\u00e9rias escolares, festas juninas e a Copa do Mundo deve aquecer o setor de turismo nos pr\u00f3ximos meses, aumentando o interesse de sergipanos por viagens dentro e fora do pa\u00eds, conforme explica a especialista Carol Asencio, agente de viagens. O per\u00edodo, considerado uma das fases mais movimentadas do ano, tende a concentrar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[],"class_list":["post-19477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sergipe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses - O Coerente\" \/>\n<meta property=\"og:description\" content=\"A combina\u00e7\u00e3o entre f\u00e9rias escolares, festas juninas e a Copa do Mundo deve aquecer o setor de turismo nos pr\u00f3ximos meses, aumentando o interesse de sergipanos por viagens dentro e fora do pa\u00eds, conforme explica a especialista Carol Asencio, agente de viagens. O per\u00edodo, considerado uma das fases mais movimentadas do ano, tende a concentrar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T17:24:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T17:24:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-10-39-28-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"769\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Abrah\u00e3o Crispim Filho\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Abrah\u00e3o Crispim Filho\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/\"},\"author\":{\"name\":\"Abrah\u00e3o Crispim Filho\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/1ed925f7992cb4d6d3b61e3d07b0ae08\"},\"headline\":\"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses\",\"datePublished\":\"2026-05-12T17:24:09+00:00\",\"dateModified\":\"2026-05-12T17:24:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/\"},\"wordCount\":278,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PHOTO-2026-05-12-10-39-28-2.jpg\",\"articleSection\":[\"Sergipe\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/\",\"name\":\"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PHOTO-2026-05-12-10-39-28-2.jpg\",\"datePublished\":\"2026-05-12T17:24:09+00:00\",\"dateModified\":\"2026-05-12T17:24:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PHOTO-2026-05-12-10-39-28-2.jpg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PHOTO-2026-05-12-10-39-28-2.jpg\",\"width\":769,\"height\":515},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/05\\\/12\\\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/1ed925f7992cb4d6d3b61e3d07b0ae08\",\"name\":\"Abrah\u00e3o Crispim Filho\",\"description\":\"Jornalista p\u00f3s-graduado em Comunica\u00e7\u00e3o.\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/crispimcoerente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/","og_locale":"pt_BR","og_type":"article","og_title":"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses - O Coerente","og_description":"A combina\u00e7\u00e3o entre f\u00e9rias escolares, festas juninas e a Copa do Mundo deve aquecer o setor de turismo nos pr\u00f3ximos meses, aumentando o interesse de sergipanos por viagens dentro e fora do pa\u00eds, conforme explica a especialista Carol Asencio, agente de viagens. O per\u00edodo, considerado uma das fases mais movimentadas do ano, tende a concentrar [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/","og_site_name":"O Coerente","article_published_time":"2026-05-12T17:24:09+00:00","article_modified_time":"2026-05-12T17:24:13+00:00","og_image":[{"width":769,"height":515,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-10-39-28-2.jpg","type":"image\/jpeg"}],"author":"Abrah\u00e3o Crispim Filho","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Abrah\u00e3o Crispim Filho","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/"},"author":{"name":"Abrah\u00e3o Crispim Filho","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/1ed925f7992cb4d6d3b61e3d07b0ae08"},"headline":"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses","datePublished":"2026-05-12T17:24:09+00:00","dateModified":"2026-05-12T17:24:13+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/"},"wordCount":278,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-10-39-28-2.jpg","articleSection":["Sergipe"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/","url":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/","name":"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-10-39-28-2.jpg","datePublished":"2026-05-12T17:24:09+00:00","dateModified":"2026-05-12T17:24:13+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-10-39-28-2.jpg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/05\/PHOTO-2026-05-12-10-39-28-2.jpg","width":769,"height":515},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2026\/05\/12\/ferias-sao-joao-e-copa-do-mundo-impulsionam-viagens-entre-sergipanos-nos-proximos-meses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"F\u00e9rias, S\u00e3o Jo\u00e3o e Copa do Mundo impulsionam viagens entre sergipanos nos pr\u00f3ximos meses"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"}},{"@type":"Person","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/1ed925f7992cb4d6d3b61e3d07b0ae08","name":"Abrah\u00e3o Crispim Filho","description":"Jornalista p\u00f3s-graduado em Comunica\u00e7\u00e3o.","url":"https:\/\/ocoerente.com.br\/se\/author\/crispimcoerente\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/19477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=19477"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/19477\/revisions"}],"predecessor-version":[{"id":19479,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/19477\/revisions\/19479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/19478"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=19477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=19477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=19477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}