{"id":19018,"date":"2026-03-24T00:54:27","date_gmt":"2026-03-24T03:54:27","guid":{"rendered":"https:\/\/ocoerente.com.br\/se\/?p=19018"},"modified":"2026-03-24T00:54:29","modified_gmt":"2026-03-24T03:54:29","slug":"alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/","title":{"rendered":"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o"},"content":{"rendered":"\n<p>O vereador Alex Melo (PRD) foi recebido pela prefeita de Aracaju, Em\u00edlia Corr\u00eaa e pelos gestores das pastas municipais: Nelson Felipe (SMTT), S\u00e9rgio Guimar\u00e3es (Emurb) e F\u00e1bio Uch\u00f4a (articula\u00e7\u00e3o Pol\u00edtica). A reuni\u00e3o ocorreu na manh\u00e3 desta segunda-feira, 16 de mar\u00e7o, na Prefeitura de Aracaju. Sempre atento \u00e0s necessidades do povo aracajuano, o parlamentar levou as demandas e pediu solu\u00e7\u00e3o nas diversas \u00e1reas.<\/p>\n\n\n\n<p>&#8220;Esse \u00e9 meu dever como vereador, estar sempre atento \u00e0s demandas dos aracajuanos e buscar solu\u00e7\u00e3o. Levei pedidos para melhorias no tr\u00e2nsito, transporte p\u00fablico e infraestrutura. Agrade\u00e7o a aten\u00e7\u00e3o da prefeita Em\u00edlia Corr\u00eaa e tamb\u00e9m dos gestores das pastas. Eles ficaram atentos \u00e0s necessidades e se colocaram \u00e0 disposi\u00e7\u00e3o para solucionar todos os meus pedidos&#8221;, garante o vereador.<\/p>\n\n\n\n<p>Alex Melo refor\u00e7ou que seu mandato est\u00e1 sempre \u00e0 servi\u00e7o do povo. &#8220;Meu gabinete est\u00e1 sempre de portas abertas para ouvir o povo. Al\u00e9m do trabalho legislativo na C\u00e2mara Municipal de Aracaju, estou tamb\u00e9m sempre nas ruas, perto da popula\u00e7\u00e3o, acompanhando cada demanda com o objetivo de buscar melhorias para cada regi\u00e3o de Aracaju&#8221;, explic<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vereador Alex Melo (PRD) foi recebido pela prefeita de Aracaju, Em\u00edlia Corr\u00eaa e pelos gestores das pastas municipais: Nelson Felipe (SMTT), S\u00e9rgio Guimar\u00e3es (Emurb) e F\u00e1bio Uch\u00f4a (articula\u00e7\u00e3o Pol\u00edtica). A reuni\u00e3o ocorreu na manh\u00e3 desta segunda-feira, 16 de mar\u00e7o, na Prefeitura de Aracaju. Sempre atento \u00e0s necessidades do povo aracajuano, o parlamentar levou as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19019,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,44],"tags":[],"class_list":["post-19018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o - O Coerente\" \/>\n<meta property=\"og:description\" content=\"O vereador Alex Melo (PRD) foi recebido pela prefeita de Aracaju, Em\u00edlia Corr\u00eaa e pelos gestores das pastas municipais: Nelson Felipe (SMTT), S\u00e9rgio Guimar\u00e3es (Emurb) e F\u00e1bio Uch\u00f4a (articula\u00e7\u00e3o Pol\u00edtica). A reuni\u00e3o ocorreu na manh\u00e3 desta segunda-feira, 16 de mar\u00e7o, na Prefeitura de Aracaju. Sempre atento \u00e0s necessidades do povo aracajuano, o parlamentar levou as [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T03:54:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T03:54:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/03\/43f1-ada4-17b42c2706f8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"headline\":\"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o\",\"datePublished\":\"2026-03-24T03:54:27+00:00\",\"dateModified\":\"2026-03-24T03:54:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/43f1-ada4-17b42c2706f8.jpg\",\"articleSection\":[\"Destaques\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/\",\"name\":\"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/43f1-ada4-17b42c2706f8.jpg\",\"datePublished\":\"2026-03-24T03:54:27+00:00\",\"dateModified\":\"2026-03-24T03:54:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/43f1-ada4-17b42c2706f8.jpg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/43f1-ada4-17b42c2706f8.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2026\\\/03\\\/24\\\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"},\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/vasticlsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o - O Coerente","og_description":"O vereador Alex Melo (PRD) foi recebido pela prefeita de Aracaju, Em\u00edlia Corr\u00eaa e pelos gestores das pastas municipais: Nelson Felipe (SMTT), S\u00e9rgio Guimar\u00e3es (Emurb) e F\u00e1bio Uch\u00f4a (articula\u00e7\u00e3o Pol\u00edtica). A reuni\u00e3o ocorreu na manh\u00e3 desta segunda-feira, 16 de mar\u00e7o, na Prefeitura de Aracaju. Sempre atento \u00e0s necessidades do povo aracajuano, o parlamentar levou as [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/","og_site_name":"O Coerente","article_published_time":"2026-03-24T03:54:27+00:00","article_modified_time":"2026-03-24T03:54:29+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/03\/43f1-ada4-17b42c2706f8.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"headline":"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o","datePublished":"2026-03-24T03:54:27+00:00","dateModified":"2026-03-24T03:54:29+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/"},"wordCount":213,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/03\/43f1-ada4-17b42c2706f8.jpg","articleSection":["Destaques","Pol\u00edtica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/","url":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/","name":"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/03\/43f1-ada4-17b42c2706f8.jpg","datePublished":"2026-03-24T03:54:27+00:00","dateModified":"2026-03-24T03:54:29+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/03\/43f1-ada4-17b42c2706f8.jpg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2026\/03\/43f1-ada4-17b42c2706f8.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2026\/03\/24\/alex-melo-e-recebido-pela-prefeita-emilia-correa-e-leva-demandas-da-populacao-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"Alex Melo \u00e9 recebido pela prefeita Em\u00edlia Corr\u00eaa e leva demandas da popula\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"},"url":"https:\/\/ocoerente.com.br\/se\/author\/vasticlsales\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/19018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=19018"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/19018\/revisions"}],"predecessor-version":[{"id":19020,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/19018\/revisions\/19020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/19019"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=19018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=19018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=19018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}