{"id":1813,"date":"2020-11-07T21:42:31","date_gmt":"2020-11-08T00:42:31","guid":{"rendered":"https:\/\/ocoerente.com.br\/se\/?p=1813"},"modified":"2020-11-07T21:42:34","modified_gmt":"2020-11-08T00:42:34","slug":"rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/","title":{"rendered":"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju"},"content":{"rendered":"\n<p>Durante entrevista na Xod\u00f3 FM, o candidato a prefeito de Aracaju, Rodrigo Valadares, destacou os seus projetos para melhorar a sa\u00fade p\u00fablica na capital sergipana. &#8220;Nosso Plano de Governo em rela\u00e7\u00e3o a sa\u00fade \u00e9 um plano que foi pensado com muito cuidado&#8221;, declarou.<\/p>\n\n\n\n<p>Segundo o candidato bolsonarista, o maior problema da sa\u00fade, tanto na gest\u00e3o de Edvaldo Nogueira quanto nos \u00faltimos 30 anos, \u00e9 a politiza\u00e7\u00e3o da sa\u00fade.<\/p>\n\n\n\n<p>&#8220;Infelizmente, a Secretaria da Sa\u00fade, historicamente, \u00e9 entregue como um pr\u00eamio para um aliado pol\u00edtico. Essa mesma sa\u00fade, ao inv\u00e9s de servir aos interesses da popula\u00e7\u00e3o, servem a interesses particulares&#8221;, disse.<\/p>\n\n\n\n<p>Em seu governo, Rodrigo afirma que isso acabar\u00e1. &#8220;Em nosso governo tudo isso vai mudar, a primeira meta \u00e9 despolitizar a sa\u00fade, n\u00e3o tendo mais um super secret\u00e1rio respons\u00e1vel por tomar todas as decis\u00f5es. A sa\u00fade ser\u00e1 feita atrav\u00e9s de um comit\u00ea gestor, com especialistas, m\u00e9dicos, enfermeiros, profissionais da sa\u00fade, conselho de sa\u00fade e, principalmente, a popula\u00e7\u00e3o em geral&#8221;.<\/p>\n\n\n\n<p>Para ele, a participa\u00e7\u00e3o dos moradores \u00e9 fundamental no reconhecimento das necessidades, a fim de ter um excelente cuidado.<\/p>\n\n\n\n<p>&#8220;A popula\u00e7\u00e3o vai opinar nas tomadas de decis\u00f5es em rela\u00e7\u00e3o a sa\u00fade, seja na secretaria, no \u00f3rg\u00e3o m\u00e1ximo ou na unidade b\u00e1sica de sa\u00fade, na UPA, no posto de sa\u00fade. Ser\u00e3o a pessoas da comunidade que v\u00e3o, atrav\u00e9s do or\u00e7amento participativo, alocar os recursos e escolher como melhor gerir sua sa\u00fade. Al\u00e9m disso, priorizaremos pessoas do bairro para trabalhar nos postos de sa\u00fade, vamos acabar com essa quest\u00e3o de cabide de emprego e loteamento pol\u00edtico&#8221;.<\/p>\n\n\n\n<p>Insatisfeito com a forma que a sa\u00fade \u00e9 gerida, o petebista fez quest\u00e3o de reafirmar que investir\u00e1 em tecnologia e transpar\u00eancia para a sa\u00fade, para que todos saibam onde est\u00e3o sendo gastos os recursos p\u00fablicos e n\u00e3o falte o b\u00e1sico \u00e0 popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>&#8220;\u00c9 inexplic\u00e1vel que a gente veja faltar medicamentos b\u00e1sicos na rede b\u00e1sica, nossa sa\u00fade n\u00e3o trata uma dor de cabe\u00e7a, uma dor de barriga, um febre, uma gripe. Se voc\u00ea for agora no HUSE e ver a \u00e1rea mais lotada, ver\u00e1 que \u00e9 a zona azul, que \u00e9 a baixa complexidade. Mas, infelizmente, o atual prefeito se esconde, foge das suas responsabilidades e nem a baixa complexidade consegue resolver&#8221;.<\/p>\n\n\n\n<p>Referindo-se a atualidade da sa\u00fade, o candidato n\u00e3o poderia esquecer de falar da pandemia do novo coronav\u00edrus que afetou todo o mundo. Em Aracaju, assim como as demais localidades, a realidade foi dura, todavia, algumas localidades sentiram um &#8216;peso maior&#8217;, devido a m\u00e1 gest\u00e3o p\u00fablica e a inefici\u00eancia em cuidar das pessoas, como \u00e9 o caso da capital sergipana.<\/p>\n\n\n\n<p>&#8220;Quando foi hora de mostrar lideran\u00e7a em um pandemia, quando foi hora de salvar vidas, de mostrar que realmente existe uma prefeitura preocupada com as vidas, o prefeito faz um hospital de campanha cinematogr\u00e1fico, em um est\u00e1dio, que atendeu menos de 400 pessoas e n\u00e3o tinha sequer uma UTI. E mais grave ainda, o mesmo dinheiro que gastou no hospital, gastou com propaganda, publicidade para divulgar o hospital. E mais grave ainda, virou caso de pol\u00edcia, a Pol\u00edcia Federa est\u00e1 em Aracaju, investigando o roubo do Covid&#8221;, lamentou.<\/p>\n\n\n\n<p>&#8220;\u00c9 muito triste, a gente viu as pessoas perderam seus entes queridos, perderem seus neg\u00f3cios, perderem seu emprego e metade do dinheiro da Covid, segundo os \u00faltimos estudos, foi roubado&#8221;, complementou.<\/p>\n\n\n\n<p>Reafirmando o comprometimento com a sa\u00fade de Aracaju, Rodrigo participou, no final do m\u00eas passado, do Ciclo de Debates do SINDIMED ( Sindicato dos M\u00e9dicos do Estado de Sergipe), onde pode explanar o seu projeto.<\/p>\n\n\n\n<p>O Sindicato, que \u00e9 presidido por Jos\u00e9 Helton, tem como vice Argemiro Filho e secret\u00e1rio Geral Jo\u00e3o Augusto, possui uma extrema import\u00e2ncia, pois segue um ciclo de debates com diversos candidatos, para facilitar que a popula\u00e7\u00e3o avalie as melhores propostas para a \u00e1rea da sa\u00fade.<\/p>\n\n\n\n<p>Na oportunidade, o candidato bolsonarista ressaltou que vai recuperar os Postos de Sa\u00fade com contrata\u00e7\u00e3o de m\u00e9dicos atrav\u00e9s do Programa M\u00e9dicos do Brasil, implanta\u00e7\u00e3o da Telemedicina com o intuito de desafogar a rede de Urg\u00eancia, viabilizar parceria com a Uni\u00e3o e Estado, bonificar os profissionais , manter o di\u00e1logo sempre com os profissionais, entre outras.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante entrevista na Xod\u00f3 FM, o candidato a prefeito de Aracaju, Rodrigo Valadares, destacou os seus projetos para melhorar a sa\u00fade p\u00fablica na capital sergipana. &#8220;Nosso Plano de Governo em rela\u00e7\u00e3o a sa\u00fade \u00e9 um plano que foi pensado com muito cuidado&#8221;, declarou. Segundo o candidato bolsonarista, o maior problema da sa\u00fade, tanto na gest\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,44,43],"tags":[],"class_list":["post-1813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-politica","category-sergipe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju - O Coerente\" \/>\n<meta property=\"og:description\" content=\"Durante entrevista na Xod\u00f3 FM, o candidato a prefeito de Aracaju, Rodrigo Valadares, destacou os seus projetos para melhorar a sa\u00fade p\u00fablica na capital sergipana. &#8220;Nosso Plano de Governo em rela\u00e7\u00e3o a sa\u00fade \u00e9 um plano que foi pensado com muito cuidado&#8221;, declarou. Segundo o candidato bolsonarista, o maior problema da sa\u00fade, tanto na gest\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-08T00:42:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-08T00:42:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/11\/rodrigovalalll.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"689\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"headline\":\"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju\",\"datePublished\":\"2020-11-08T00:42:31+00:00\",\"dateModified\":\"2020-11-08T00:42:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/\"},\"wordCount\":759,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rodrigovalalll.jpg\",\"articleSection\":[\"Destaques\",\"Pol\u00edtica\",\"Sergipe\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/\",\"name\":\"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rodrigovalalll.jpg\",\"datePublished\":\"2020-11-08T00:42:31+00:00\",\"dateModified\":\"2020-11-08T00:42:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rodrigovalalll.jpg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rodrigovalalll.jpg\",\"width\":1080,\"height\":689},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2020\\\/11\\\/07\\\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"},\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/vasticlsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/","og_locale":"pt_BR","og_type":"article","og_title":"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju - O Coerente","og_description":"Durante entrevista na Xod\u00f3 FM, o candidato a prefeito de Aracaju, Rodrigo Valadares, destacou os seus projetos para melhorar a sa\u00fade p\u00fablica na capital sergipana. &#8220;Nosso Plano de Governo em rela\u00e7\u00e3o a sa\u00fade \u00e9 um plano que foi pensado com muito cuidado&#8221;, declarou. Segundo o candidato bolsonarista, o maior problema da sa\u00fade, tanto na gest\u00e3o [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/","og_site_name":"O Coerente","article_published_time":"2020-11-08T00:42:31+00:00","article_modified_time":"2020-11-08T00:42:34+00:00","og_image":[{"width":1080,"height":689,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/11\/rodrigovalalll.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"headline":"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju","datePublished":"2020-11-08T00:42:31+00:00","dateModified":"2020-11-08T00:42:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/"},"wordCount":759,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/11\/rodrigovalalll.jpg","articleSection":["Destaques","Pol\u00edtica","Sergipe"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/","url":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/","name":"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/11\/rodrigovalalll.jpg","datePublished":"2020-11-08T00:42:31+00:00","dateModified":"2020-11-08T00:42:34+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/11\/rodrigovalalll.jpg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/11\/rodrigovalalll.jpg","width":1080,"height":689},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2020\/11\/07\/rodrigo-valadares-destaca-seus-projetos-para-a-saude-em-aracaju\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"Rodrigo Valadares destaca seus projetos para a sa\u00fade em Aracaju"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"},"url":"https:\/\/ocoerente.com.br\/se\/author\/vasticlsales\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/1813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=1813"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/1813\/revisions"}],"predecessor-version":[{"id":1815,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/1813\/revisions\/1815"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/1814"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=1813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=1813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=1813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}