{"id":14173,"date":"2025-05-05T18:05:13","date_gmt":"2025-05-05T21:05:13","guid":{"rendered":"https:\/\/ocoerente.com.br\/se\/?p=14173"},"modified":"2025-05-05T18:05:14","modified_gmt":"2025-05-05T21:05:14","slug":"governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/","title":{"rendered":"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera"},"content":{"rendered":"\n<p><em>Modalidades coletivas abrem a programa\u00e7\u00e3o da 41\u00aa edi\u00e7\u00e3o, que re\u00fane mais de 11 mil estudantes de todo o estado, em 28 modalidades esportivas e paramodalidades<\/em><\/p>\n\n\n\n<p>A edi\u00e7\u00e3o de n\u00famero 41 dos Jogos da Primavera de Sergipe come\u00e7a na pr\u00f3xima segunda, 5 de maio, e promete movimentar o esporte escolar no estado at\u00e9 o dia 13 de junho. A competi\u00e7\u00e3o, que este ano reuniu um n\u00famero recorde de 481 escolas inscritas \u2014 sendo 238 estaduais, 106 municipais, 133 particulares e 4 federais \u2014, contar\u00e1 com a participa\u00e7\u00e3o de 11.230 alunos distribu\u00eddos em 28 modalidades e paramodalidades.<\/p>\n\n\n\n<p>Na primeira semana, as modalidades coletivas abrem a programa\u00e7\u00e3o, com destaque para o futsal, v\u00f4lei e basquete. As partidas de futsal ser\u00e3o realizadas diariamente, tanto na capital quanto no interior, com disputas nas cidades de Nossa Senhora do Socorro, Est\u00e2ncia, S\u00e3o Crist\u00f3v\u00e3o e Itabaiana, o dia inteiro. Em Aracaju, os jogos de futsal acontecem no Gin\u00e1sio Const\u00e2ncio Vieira e no Col\u00e9gio Estadual Professor Jacinto Uch\u00f4a, no per\u00edodo da tarde, a partir das 13h. Na segunda-feira, o futsal ser\u00e1 realizado no Col\u00e9gio Santos Dumont, no bairro Aeroporto.<\/p>\n\n\n\n<p>Na quarta-feira, 7, o ciclismo estreia no kart\u00f3dromo, localizado na Orla de Atalaia, durante todo o dia. J\u00e1 no s\u00e1bado, 11, o p\u00fablico poder\u00e1 acompanhar, na quadra poliesportiva Geraldo de Oliveira, mais conhecida como Gerald\u00e3o, em Aracaju, as competi\u00e7\u00f5es de v\u00f4lei sentado, das 8h \u00e0s 12h. A programa\u00e7\u00e3o di\u00e1ria completa poder\u00e1 ser acompanhada pelo perfil oficial da Secretaria de Estado do Esporte e Lazer no Instagram: @esporte.sergipe.<\/p>\n\n\n\n<p>Neste ano, a grande novidade dos Jogos da Primavera \u00e9 a inclus\u00e3o do skate como modalidade oficial, contando com 34 atletas inscritos, entre meninos e meninas. Ao longo do evento, ser\u00e3o disputadas 657 provas, que tamb\u00e9m funcionar\u00e3o como seletiva para importantes competi\u00e7\u00f5es nacionais, como os Jogos da Juventude e os Jogos Escolares Brasileiros (JEB\u2019s).<\/p>\n\n\n\n<p>Ap\u00f3s o primeiro ciclo de competi\u00e7\u00f5es, haver\u00e1 uma breve pausa para o recesso escolar, com retorno previsto para o dia 28 de julho e encerramento oficial no dia 8 de agosto.<br>De acordo com a secret\u00e1ria de Estado do Esporte e Lazer, Mariana Dantas, a realiza\u00e7\u00e3o dos Jogos da Primavera refor\u00e7a o compromisso do Governo de Sergipe com o est\u00edmulo \u00e0 pr\u00e1tica esportiva desde a escola. \u201cEstamos muito felizes em promover mais uma edi\u00e7\u00e3o dos Jogos da Primavera, um evento tradicional que n\u00e3o s\u00f3 integra nossos estudantes, como tamb\u00e9m revela talentos e contribui para a forma\u00e7\u00e3o cidad\u00e3 dos jovens. Este ano, batemos recorde de inscri\u00e7\u00f5es e ampliamos ainda mais a diversidade das modalidades, com a chegada do skate, o que \u00e9 motivo de grande orgulho para todos n\u00f3s\u201d, destacou a secret\u00e1ria.<\/p>\n\n\n\n<p>Governo de Sergipe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modalidades coletivas abrem a programa\u00e7\u00e3o da 41\u00aa edi\u00e7\u00e3o, que re\u00fane mais de 11 mil estudantes de todo o estado, em 28 modalidades esportivas e paramodalidades A edi\u00e7\u00e3o de n\u00famero 41 dos Jogos da Primavera de Sergipe come\u00e7a na pr\u00f3xima segunda, 5 de maio, e promete movimentar o esporte escolar no estado at\u00e9 o dia 13 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,46],"tags":[],"class_list":["post-14173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-esporte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera - O Coerente\" \/>\n<meta property=\"og:description\" content=\"Modalidades coletivas abrem a programa\u00e7\u00e3o da 41\u00aa edi\u00e7\u00e3o, que re\u00fane mais de 11 mil estudantes de todo o estado, em 28 modalidades esportivas e paramodalidades A edi\u00e7\u00e3o de n\u00famero 41 dos Jogos da Primavera de Sergipe come\u00e7a na pr\u00f3xima segunda, 5 de maio, e promete movimentar o esporte escolar no estado at\u00e9 o dia 13 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-05T21:05:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T21:05:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/05\/1c3589ff.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"headline\":\"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera\",\"datePublished\":\"2025-05-05T21:05:13+00:00\",\"dateModified\":\"2025-05-05T21:05:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/\"},\"wordCount\":478,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1c3589ff.jpg\",\"articleSection\":[\"Destaques\",\"Esporte\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/\",\"name\":\"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1c3589ff.jpg\",\"datePublished\":\"2025-05-05T21:05:13+00:00\",\"dateModified\":\"2025-05-05T21:05:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1c3589ff.jpg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1c3589ff.jpg\",\"width\":1100,\"height\":610,\"caption\":\"Foto: Ascom Seel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/05\\\/05\\\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"},\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/vasticlsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera - O Coerente","og_description":"Modalidades coletivas abrem a programa\u00e7\u00e3o da 41\u00aa edi\u00e7\u00e3o, que re\u00fane mais de 11 mil estudantes de todo o estado, em 28 modalidades esportivas e paramodalidades A edi\u00e7\u00e3o de n\u00famero 41 dos Jogos da Primavera de Sergipe come\u00e7a na pr\u00f3xima segunda, 5 de maio, e promete movimentar o esporte escolar no estado at\u00e9 o dia 13 [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/","og_site_name":"O Coerente","article_published_time":"2025-05-05T21:05:13+00:00","article_modified_time":"2025-05-05T21:05:14+00:00","og_image":[{"width":1100,"height":610,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/05\/1c3589ff.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"headline":"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera","datePublished":"2025-05-05T21:05:13+00:00","dateModified":"2025-05-05T21:05:14+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/"},"wordCount":478,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/05\/1c3589ff.jpg","articleSection":["Destaques","Esporte"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/","url":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/","name":"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/05\/1c3589ff.jpg","datePublished":"2025-05-05T21:05:13+00:00","dateModified":"2025-05-05T21:05:14+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/05\/1c3589ff.jpg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/05\/1c3589ff.jpg","width":1100,"height":610,"caption":"Foto: Ascom Seel"},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2025\/05\/05\/governo-de-sergipe-divulga-programacao-da-primeira-semana-do-41o-jogos-da-primavera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"Governo de Sergipe divulga programa\u00e7\u00e3o da primeira semana do 41\u00ba Jogos da Primavera"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"},"url":"https:\/\/ocoerente.com.br\/se\/author\/vasticlsales\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/14173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=14173"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/14173\/revisions"}],"predecessor-version":[{"id":14175,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/14173\/revisions\/14175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/14174"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=14173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=14173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=14173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}