{"id":12699,"date":"2025-02-20T14:54:09","date_gmt":"2025-02-20T17:54:09","guid":{"rendered":"https:\/\/ocoerente.com.br\/se\/?p=12699"},"modified":"2025-02-20T14:54:10","modified_gmt":"2025-02-20T17:54:10","slug":"katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/","title":{"rendered":"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade"},"content":{"rendered":"\n<p>O presidente da Assembleia Legislativa do Estado de Sergipe, deputado Jeferson Andrade, saiu em defesa e prestou solidariedade \u00e0 deputada federal Katarina Feitoza (PSD), que foi recentemente constrangida no Plen\u00e1rio da C\u00e2mara Federal por alguns parlamentares ultraconservadores. Esses direitistas radicais impediram que a deputada, que \u00e9 3\u00aa Secret\u00e1ria da C\u00e2mara, presidisse temporariamente a sess\u00e3o no lugar do presidente Hugo Motta, causando tumultos e dist\u00farbios no Plen\u00e1rio.<\/p>\n\n\n\n<p>\u201cFoi um ato insano e mis\u00f3gino contra uma deputada federal competente e \u00edntegra, uma leg\u00edtima representante do povo sergipano, que estava cumprindo suas fun\u00e7\u00f5es constitucionais a pedido do pr\u00f3prio presidente da Casa. Uma atitude preconceituosa e irrespons\u00e1vel contra todas as mulheres brasileiras que, naquele instante, a deputada Katarina Feitoza representava\u201d, afirmou o deputado Jeferson Andrade.<\/p>\n\n\n\n<p>A deputada Katarina Feitoza enfrentou os manifestantes com firmeza, repreendeu-os moralmente e encerrou a sess\u00e3o.<\/p>\n\n\n\n<p>O deputado Jeferson Andrade registrou o fato na Assembleia Legislativa de Sergipe e prestou total e irrestrita solidariedade \u00e0 deputada federal Katarina Feitoza.<\/p>\n\n\n\n<p>\u201cEm meu nome, em nome da Alese e de todos os sergipanos, cumprimento a deputada Katarina Feitoza, as demais deputadas federais dos estados, as servidoras da C\u00e2mara Federal e todas as mulheres brasileiras que foram afrontadas naquela cena lament\u00e1vel por um ato grosseiro, desrespeitoso e inconstitucional. Devo registrar e agradecer tamb\u00e9m ao deputado Hugo Motta, presidente da C\u00e2mara Federal, pelo pronto restabelecimento da ordem e pelo total apoio \u00e0 nossa deputada. Katarina, amiga, siga em frente. Sergipe e o Brasil t\u00eam por voc\u00ea todo o respeito, considera\u00e7\u00e3o e muito orgulho\u201d, finalizou o deputado Jeferson Andrade, presidente da Assembleia Legislativa do Estado de Sergipe.<\/p>\n\n\n\n<p>Fonte: <a href=\"https:\/\/folhadesergipe.com\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/\">Folha de Sergipe<\/a><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da Assembleia Legislativa do Estado de Sergipe, deputado Jeferson Andrade, saiu em defesa e prestou solidariedade \u00e0 deputada federal Katarina Feitoza (PSD), que foi recentemente constrangida no Plen\u00e1rio da C\u00e2mara Federal por alguns parlamentares ultraconservadores. Esses direitistas radicais impediram que a deputada, que \u00e9 3\u00aa Secret\u00e1ria da C\u00e2mara, presidisse temporariamente a sess\u00e3o no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,44],"tags":[],"class_list":["post-12699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade - O Coerente\" \/>\n<meta property=\"og:description\" content=\"O presidente da Assembleia Legislativa do Estado de Sergipe, deputado Jeferson Andrade, saiu em defesa e prestou solidariedade \u00e0 deputada federal Katarina Feitoza (PSD), que foi recentemente constrangida no Plen\u00e1rio da C\u00e2mara Federal por alguns parlamentares ultraconservadores. Esses direitistas radicais impediram que a deputada, que \u00e9 3\u00aa Secret\u00e1ria da C\u00e2mara, presidisse temporariamente a sess\u00e3o no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-20T17:54:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T17:54:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/02\/300x244.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"244\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"headline\":\"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade\",\"datePublished\":\"2025-02-20T17:54:09+00:00\",\"dateModified\":\"2025-02-20T17:54:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/\"},\"wordCount\":290,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/300x244.jpeg\",\"articleSection\":[\"Destaques\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/\",\"name\":\"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/300x244.jpeg\",\"datePublished\":\"2025-02-20T17:54:09+00:00\",\"dateModified\":\"2025-02-20T17:54:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/300x244.jpeg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/300x244.jpeg\",\"width\":300,\"height\":244},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/02\\\/20\\\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"},\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/vasticlsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/","og_locale":"pt_BR","og_type":"article","og_title":"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade - O Coerente","og_description":"O presidente da Assembleia Legislativa do Estado de Sergipe, deputado Jeferson Andrade, saiu em defesa e prestou solidariedade \u00e0 deputada federal Katarina Feitoza (PSD), que foi recentemente constrangida no Plen\u00e1rio da C\u00e2mara Federal por alguns parlamentares ultraconservadores. Esses direitistas radicais impediram que a deputada, que \u00e9 3\u00aa Secret\u00e1ria da C\u00e2mara, presidisse temporariamente a sess\u00e3o no [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/","og_site_name":"O Coerente","article_published_time":"2025-02-20T17:54:09+00:00","article_modified_time":"2025-02-20T17:54:10+00:00","og_image":[{"width":300,"height":244,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/02\/300x244.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"headline":"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade","datePublished":"2025-02-20T17:54:09+00:00","dateModified":"2025-02-20T17:54:10+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/"},"wordCount":290,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/02\/300x244.jpeg","articleSection":["Destaques","Pol\u00edtica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/","url":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/","name":"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/02\/300x244.jpeg","datePublished":"2025-02-20T17:54:09+00:00","dateModified":"2025-02-20T17:54:10+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/02\/300x244.jpeg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/02\/300x244.jpeg","width":300,"height":244},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2025\/02\/20\/katarina-e-todas-as-mulheres-merecem-respeito-diz-jeferson-andrade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"\u201cKatarina e todas as mulheres merecem respeito\u201d, diz Jeferson Andrade"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"},"url":"https:\/\/ocoerente.com.br\/se\/author\/vasticlsales\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/12699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=12699"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/12699\/revisions"}],"predecessor-version":[{"id":12701,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/12699\/revisions\/12701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/12700"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=12699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=12699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=12699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}