{"id":12309,"date":"2025-01-18T00:26:11","date_gmt":"2025-01-18T03:26:11","guid":{"rendered":"https:\/\/ocoerente.com.br\/se\/?p=12309"},"modified":"2025-01-18T00:26:12","modified_gmt":"2025-01-18T03:26:12","slug":"contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/","title":{"rendered":"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda"},"content":{"rendered":"\n<p><em>Prazo para reativa\u00e7\u00e3o \u00e9 de seis meses ap\u00f3s a notifica\u00e7\u00e3o enviada pela secretaria<\/em><\/p>\n\n\n\n<p>Mais de 520 contribuintes sergipanos tiveram a Inscri\u00e7\u00e3o Estadual (IE) cancelada pela Secretaria de Estado da Fazenda (Sefaz) em 2024. A medida, que impacta diretamente o funcionamento dos estabelecimentos comerciais, \u00e9 causada principalmente pelo descumprimento de obriga\u00e7\u00f5es por parte dos empres\u00e1rios.&nbsp;&nbsp;<\/p>\n\n\n\n<p>A inscri\u00e7\u00e3o estadual \u00e9 o registro que toda empresa precisa ter para comercializar produtos f\u00edsicos, sendo necess\u00e1ria para o recolhimento do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS) e a emiss\u00e3o de notas fiscais. O documento funciona como um registro no estado onde ela atua, garantindo que o estabelecimento \u00e9 devidamente regularizado junto ao Fisco.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Entre os motivos que levaram ao cancelamento est\u00e3o a falta de recolhimento do ICMS, aus\u00eancia de atualiza\u00e7\u00e3o de endere\u00e7o, n\u00e3o entrega da Escritura\u00e7\u00e3o Fiscal Digital (EFD) \u2013 arquivo que cont\u00e9m diversos tipos de registros de interesse dos fiscos municipais, estaduais e federal \u2013 e a inatividade prolongada de empresas.<\/p>\n\n\n\n<p>O cancelamento da inscri\u00e7\u00e3o traz uma s\u00e9rie de preju\u00edzos para o contribuinte: ele fica impedido de emitir notas fiscais, o que inviabiliza a comercializa\u00e7\u00e3o de produtos, e certid\u00f5es negativas, documentos essenciais para participa\u00e7\u00e3o em licita\u00e7\u00f5es e outros processos administrativos. Tamb\u00e9m n\u00e3o poder\u00e3o realizar compras de insumos e mercadorias, j\u00e1 que os fornecedores est\u00e3o proibidos de emitir notas fiscais para contribuintes cancelados.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u201c\u00c9 importante destacar que antes de realizar o cancelamento, a Secretaria da Fazenda notificou todos esses empres\u00e1rios por meio do domic\u00edlio tribut\u00e1rio eletr\u00f4nico e da publica\u00e7\u00e3o de editais no Di\u00e1rio Eletr\u00f4nico Fiscal. Eles foram orientados a regularizar essa situa\u00e7\u00e3o e informados sobre o prazo para realizar o procedimento\u201d, explica a auditora fiscal da Sefaz Bruna Vieira.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Regulariza\u00e7\u00e3o&nbsp;<\/strong><br>Para a reativa\u00e7\u00e3o da inscri\u00e7\u00e3o ser feita, \u00e9 preciso que as obriga\u00e7\u00f5es que motivaram o cancelamento sejam cumpridas. Por exemplo, caso o motivo tenha sido a falta de entrega da EFD, o contribuinte deve regularizar essa entrega e efetuar os pagamentos devidos.<\/p>\n\n\n\n<p>Em caso de atualiza\u00e7\u00e3o de endere\u00e7o, ele deve provar que reside no novo local e anexar a documenta\u00e7\u00e3o pertinente. Ap\u00f3s a comprova\u00e7\u00e3o, ele deve realizar o pedido de reativa\u00e7\u00e3o utilizando o E-doc. O prazo para a solicita\u00e7\u00e3o \u00e9 de seis meses a partir da publica\u00e7\u00e3o do edital de cancelamento no Di\u00e1rio Eletr\u00f4nico Fiscal.<\/p>\n\n\n\n<p>Para verificar se a inscri\u00e7\u00e3o foi cancelada, os empres\u00e1rios podem acessar o site da Sefaz e clicar no \u00edcone \u2018Acesso\u2019, informando o n\u00famero da IE e a senha. Outra op\u00e7\u00e3o \u00e9 acessar o site da Sefaz, na se\u00e7\u00e3o de \u2018Servi\u00e7os Online\u2019, e verificar o \u2018Di\u00e1rio Eletr\u00f4nico da Sefaz\u2019, digitando o n\u00famero da inscri\u00e7\u00e3o estadual.&nbsp;<\/p>\n\n\n\n<p>\u201c\u00c9 fundamental que o contribuinte esteja atento ao seu e-mail para compreender as raz\u00f5es do cancelamento e proceder a regulariza\u00e7\u00e3o dentro do prazo legal. Caso a situa\u00e7\u00e3o n\u00e3o seja resolvida, ele sofrer\u00e1 as penalidades previstas em lei e ter\u00e1 o funcionamento da sua empresa afetado\u201d, refor\u00e7a Bruna Vieira.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Em caso de d\u00favidas, o contribuinte pode procurar um dos postos de atendimento da Sefaz nos Centros de Atendimento ao Cidad\u00e3o (Ceacs) e receber todas as orienta\u00e7\u00f5es necess\u00e1rias para reativar a inscri\u00e7\u00e3o.<\/p>\n\n\n\n<p>Governo de Sergipe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prazo para reativa\u00e7\u00e3o \u00e9 de seis meses ap\u00f3s a notifica\u00e7\u00e3o enviada pela secretaria Mais de 520 contribuintes sergipanos tiveram a Inscri\u00e7\u00e3o Estadual (IE) cancelada pela Secretaria de Estado da Fazenda (Sefaz) em 2024. A medida, que impacta diretamente o funcionamento dos estabelecimentos comerciais, \u00e9 causada principalmente pelo descumprimento de obriga\u00e7\u00f5es por parte dos empres\u00e1rios.&nbsp;&nbsp; A [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,55],"tags":[],"class_list":["post-12309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-economia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda - O Coerente\" \/>\n<meta property=\"og:description\" content=\"Prazo para reativa\u00e7\u00e3o \u00e9 de seis meses ap\u00f3s a notifica\u00e7\u00e3o enviada pela secretaria Mais de 520 contribuintes sergipanos tiveram a Inscri\u00e7\u00e3o Estadual (IE) cancelada pela Secretaria de Estado da Fazenda (Sefaz) em 2024. A medida, que impacta diretamente o funcionamento dos estabelecimentos comerciais, \u00e9 causada principalmente pelo descumprimento de obriga\u00e7\u00f5es por parte dos empres\u00e1rios.&nbsp;&nbsp; A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-18T03:26:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-18T03:26:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/01\/c323b86.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"headline\":\"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda\",\"datePublished\":\"2025-01-18T03:26:11+00:00\",\"dateModified\":\"2025-01-18T03:26:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/\"},\"wordCount\":598,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/c323b86.jpg\",\"articleSection\":[\"Destaques\",\"Economia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/\",\"name\":\"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/c323b86.jpg\",\"datePublished\":\"2025-01-18T03:26:11+00:00\",\"dateModified\":\"2025-01-18T03:26:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/c323b86.jpg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/c323b86.jpg\",\"width\":1100,\"height\":610,\"caption\":\"Foto: Ascom Sefaz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2025\\\/01\\\/18\\\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"},\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/vasticlsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/","og_locale":"pt_BR","og_type":"article","og_title":"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda - O Coerente","og_description":"Prazo para reativa\u00e7\u00e3o \u00e9 de seis meses ap\u00f3s a notifica\u00e7\u00e3o enviada pela secretaria Mais de 520 contribuintes sergipanos tiveram a Inscri\u00e7\u00e3o Estadual (IE) cancelada pela Secretaria de Estado da Fazenda (Sefaz) em 2024. A medida, que impacta diretamente o funcionamento dos estabelecimentos comerciais, \u00e9 causada principalmente pelo descumprimento de obriga\u00e7\u00f5es por parte dos empres\u00e1rios.&nbsp;&nbsp; A [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/","og_site_name":"O Coerente","article_published_time":"2025-01-18T03:26:11+00:00","article_modified_time":"2025-01-18T03:26:12+00:00","og_image":[{"width":1100,"height":610,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/01\/c323b86.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"headline":"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda","datePublished":"2025-01-18T03:26:11+00:00","dateModified":"2025-01-18T03:26:12+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/"},"wordCount":598,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/01\/c323b86.jpg","articleSection":["Destaques","Economia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/","url":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/","name":"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/01\/c323b86.jpg","datePublished":"2025-01-18T03:26:11+00:00","dateModified":"2025-01-18T03:26:12+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/01\/c323b86.jpg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2025\/01\/c323b86.jpg","width":1100,"height":610,"caption":"Foto: Ascom Sefaz"},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2025\/01\/18\/contribuintes-que-tiveram-inscricao-estadual-cancelada-precisam-se-regularizar-junto-a-secretaria-da-fazenda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"Contribuintes que tiveram inscri\u00e7\u00e3o estadual cancelada precisam se regularizar junto \u00e0 Secretaria da Fazenda"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"},"url":"https:\/\/ocoerente.com.br\/se\/author\/vasticlsales\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/12309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=12309"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/12309\/revisions"}],"predecessor-version":[{"id":12311,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/12309\/revisions\/12311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/12310"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=12309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=12309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=12309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}