{"id":11545,"date":"2024-11-05T07:43:35","date_gmt":"2024-11-05T10:43:35","guid":{"rendered":"https:\/\/ocoerente.com.br\/se\/?p=11545"},"modified":"2024-11-05T07:43:37","modified_gmt":"2024-11-05T10:43:37","slug":"projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese","status":"publish","type":"post","link":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/","title":{"rendered":"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese"},"content":{"rendered":"\n<p><em>Nova legisla\u00e7\u00e3o garante mais seguran\u00e7a jur\u00eddica para empresas e melhora ambiente de neg\u00f3cios<\/em><\/p>\n\n\n\n<p>O Projeto de Lei de n\u2070 366\/2024, que altera a legisla\u00e7\u00e3o do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS), foi aprovado nesta quinta-feira, 31, na Assembleia Legislativa de Sergipe (Alese). Entre as mudan\u00e7as est\u00e1 a possibilidade do reconhecimento espont\u00e2neo de d\u00e9bitos por parte dos contribuintes, de forma a evitar eventuais puni\u00e7\u00f5es.<\/p>\n\n\n\n<p>Conforme o projeto, os contribuintes que possuem pend\u00eancias junto ao Fisco poder\u00e3o, de forma espont\u00e2nea, reconhecer essas d\u00edvidas e negoci\u00e1-las antes de serem autuadas pela Secretaria de Estado da Fazenda (Sefaz). Caso o d\u00e9bito n\u00e3o seja quitado ou parcelado, ele ser\u00e1 devidamente inscrito na d\u00edvida ativa para posterior cobran\u00e7a.<\/p>\n\n\n\n<p>A proposta est\u00e1 alinhada aos princ\u00edpios da conformidade tribut\u00e1ria, ou seja, quando o \u00f3rg\u00e3o fiscalizador orienta e estimula as empresas a cumprirem a legisla\u00e7\u00e3o antes de adotar qualquer a\u00e7\u00e3o punitiva.<\/p>\n\n\n\n<p>\u201cEstamos buscando construir cada vez mais um ambiente de confian\u00e7a entre a Sefaz e os contribuintes. A nossa ideia \u00e9 estimular a autorregulariza\u00e7\u00e3o, oferecendo a oportunidade para que todos resolvam suas pend\u00eancias e cumpram a legisla\u00e7\u00e3o. A aprova\u00e7\u00e3o desse projeto ajuda a trazer ainda mais seguran\u00e7a jur\u00eddica para o nosso estado, j\u00e1 que garante \u00e0s empresas condi\u00e7\u00f5es que evitem a penaliza\u00e7\u00e3o autom\u00e1tica por conta da exist\u00eancia de d\u00e9bitos\u201d, explica a secret\u00e1ria de Estado da Fazenda, Sarah Tarsila.<\/p>\n\n\n\n<p>O PL aprovado pelos parlamentares \u00e9 mais uma medida adotada pelo Governo de Sergipe para implementar uma mudan\u00e7a no car\u00e1ter de atua\u00e7\u00e3o da Sefaz, substituindo o car\u00e1ter punitivo do Fisco pelo de parceiro do contribuinte. A principal delas foi a cria\u00e7\u00e3o, no segundo semestre do ano passado, do programa Amigo da Gente. A iniciativa tem como foco valorizar aqueles empres\u00e1rios que cumprem a legisla\u00e7\u00e3o e precisam receber um olhar mais atento da gest\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>A ideia \u00e9 oferecer benef\u00edcios para aqueles que est\u00e3o em dia com as suas obriga\u00e7\u00f5es, como por exemplo a oferta de tratamento diferenciado nos procedimentos de controles de mercadorias em tr\u00e2nsito, canais de atendimento especial na secretaria, prioridade no julgamento de processos administrativos e redu\u00e7\u00e3o de multas fiscais. A Sefaz classifica a cada quatro meses os contribuintes em tr\u00eas categorias (ouro, prata e bronze), garantindo as vantagens para os melhores classificados.<\/p>\n\n\n\n<p><strong>Calend\u00e1rio de pagamento<\/strong><\/p>\n\n\n\n<p>Outra mudan\u00e7a prevista no PL 366\/2024 \u00e9 que, caso o vencimento do ICMS coincida com datas em que n\u00e3o exista expediente banc\u00e1rio, o pagamento poder\u00e1 ser feito no pr\u00f3ximo dia \u00fatil, desde que permane\u00e7a dentro do m\u00eas de vencimento original. Caso essa prorroga\u00e7\u00e3o ultrapasse o m\u00eas do vencimento original do tributo, ele dever\u00e1 ser pago no \u00faltimo dia \u00fatil do referido m\u00eas.&nbsp;<\/p>\n\n\n\n<p>\u201cIsso vai facilitar a vida do empres\u00e1rio, pois ele passar\u00e1 a saber com anteced\u00eancia quando dever\u00e1 fazer esse pagamento. Hoje essa decis\u00e3o \u00e9 sempre tomada pela Sefaz por meio de portarias e isso acaba gerando muitas d\u00favidas sobre quando vai haver uma prorroga\u00e7\u00e3o\u201d, destaca a secret\u00e1ria Sarah Tarsila.<\/p>\n\n\n\n<p>O projeto tamb\u00e9m traz altera\u00e7\u00f5es nos percentuais das multas aplicadas em casos de descumprimento da legisla\u00e7\u00e3o tribut\u00e1ria, adequando o regulamento sergipano ao que estabelece o Supremo Tribunal Federal no que diz respeito ao indicador m\u00e1ximo a ser aplicado.<\/p>\n\n\n\n<p>A nova lei tamb\u00e9m passa a estabelecer penalidade para os contribuintes que fa\u00e7am o registro indevido de cr\u00e9ditos tribut\u00e1rios em sua Escritura\u00e7\u00e3o Fiscal Digital (EFD), o documento que cont\u00e9m todas as informa\u00e7\u00f5es de apura\u00e7\u00f5es de impostos da empresa e \u00e9 enviada mensalmente para a Sefaz. Esses cr\u00e9ditos, na pr\u00e1tica, funcionam como uma d\u00edvida do Estado perante o contribuinte e que podem ser utilizados na compensa\u00e7\u00e3o de tributos pagos em outras opera\u00e7\u00f5es.<\/p>\n\n\n\n<p>Aqueles que adotarem tal iniciativa ser\u00e3o punidos com a aplica\u00e7\u00e3o de multa no valor correspondente ao cr\u00e9dito registrado de forma indevida. \u201cEssa iniciativa do Governo do Estado, por meio da Sefaz, garante avan\u00e7os importantes que viabilizam a boa gest\u00e3o financeira de seus d\u00e9bitos e melhoram o sistema de arrecada\u00e7\u00e3o do Estado, que tem obtido resultados importantes, por meio de iniciativas como o Amigo da Gente\u201d, informou o l\u00edder do governo na Alese, deputado Cristiano Cavalcante.<\/p>\n\n\n\n<p>Governo de Sergipe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nova legisla\u00e7\u00e3o garante mais seguran\u00e7a jur\u00eddica para empresas e melhora ambiente de neg\u00f3cios O Projeto de Lei de n\u2070 366\/2024, que altera a legisla\u00e7\u00e3o do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS), foi aprovado nesta quinta-feira, 31, na Assembleia Legislativa de Sergipe (Alese). Entre as mudan\u00e7as est\u00e1 a possibilidade do reconhecimento espont\u00e2neo de d\u00e9bitos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11546,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,44],"tags":[],"class_list":["post-11545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese - O Coerente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese - O Coerente\" \/>\n<meta property=\"og:description\" content=\"Nova legisla\u00e7\u00e3o garante mais seguran\u00e7a jur\u00eddica para empresas e melhora ambiente de neg\u00f3cios O Projeto de Lei de n\u2070 366\/2024, que altera a legisla\u00e7\u00e3o do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS), foi aprovado nesta quinta-feira, 31, na Assembleia Legislativa de Sergipe (Alese). Entre as mudan\u00e7as est\u00e1 a possibilidade do reconhecimento espont\u00e2neo de d\u00e9bitos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/\" \/>\n<meta property=\"og:site_name\" content=\"O Coerente\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-05T10:43:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-05T10:43:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/11\/4e89f10.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"headline\":\"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese\",\"datePublished\":\"2024-11-05T10:43:35+00:00\",\"dateModified\":\"2024-11-05T10:43:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/\"},\"wordCount\":766,\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/4e89f10.jpeg\",\"articleSection\":[\"Destaques\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/\",\"name\":\"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese - O Coerente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/4e89f10.jpeg\",\"datePublished\":\"2024-11-05T10:43:35+00:00\",\"dateModified\":\"2024-11-05T10:43:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/4e89f10.jpeg\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/4e89f10.jpeg\",\"width\":1100,\"height\":610,\"caption\":\"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese \\\/ Foto: Gabriel Jesus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/2024\\\/11\\\/05\\\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#website\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/\",\"name\":\"O Coerente\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/#\\\/schema\\\/person\\\/cc6bfd9fbca465e23543b0c963d8d037\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"contentUrl\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\",\"width\":50,\"height\":50,\"caption\":\"Reda\u00e7\u00e3o\"},\"logo\":{\"@id\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ocoerente-1.png\"},\"url\":\"https:\\\/\\\/ocoerente.com.br\\\/se\\\/author\\\/vasticlsales\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese - O Coerente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese - O Coerente","og_description":"Nova legisla\u00e7\u00e3o garante mais seguran\u00e7a jur\u00eddica para empresas e melhora ambiente de neg\u00f3cios O Projeto de Lei de n\u2070 366\/2024, que altera a legisla\u00e7\u00e3o do Imposto sobre Circula\u00e7\u00e3o de Mercadorias e Servi\u00e7os (ICMS), foi aprovado nesta quinta-feira, 31, na Assembleia Legislativa de Sergipe (Alese). Entre as mudan\u00e7as est\u00e1 a possibilidade do reconhecimento espont\u00e2neo de d\u00e9bitos [&hellip;]","og_url":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/","og_site_name":"O Coerente","article_published_time":"2024-11-05T10:43:35+00:00","article_modified_time":"2024-11-05T10:43:37+00:00","og_image":[{"width":1100,"height":610,"url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/11\/4e89f10.jpeg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/#article","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"headline":"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese","datePublished":"2024-11-05T10:43:35+00:00","dateModified":"2024-11-05T10:43:37+00:00","mainEntityOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/"},"wordCount":766,"publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/11\/4e89f10.jpeg","articleSection":["Destaques","Pol\u00edtica"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/","url":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/","name":"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese - O Coerente","isPartOf":{"@id":"https:\/\/ocoerente.com.br\/se\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/#primaryimage"},"image":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/#primaryimage"},"thumbnailUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/11\/4e89f10.jpeg","datePublished":"2024-11-05T10:43:35+00:00","dateModified":"2024-11-05T10:43:37+00:00","breadcrumb":{"@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/#primaryimage","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/11\/4e89f10.jpeg","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2024\/11\/4e89f10.jpeg","width":1100,"height":610,"caption":"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese \/ Foto: Gabriel Jesus"},{"@type":"BreadcrumbList","@id":"https:\/\/ocoerente.com.br\/se\/2024\/11\/05\/projeto-de-lei-que-estimula-a-autorregularizacao-de-contribuintes-e-aprovado-na-alese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ocoerente.com.br\/se\/"},{"@type":"ListItem","position":2,"name":"Projeto de Lei que estimula a autorregulariza\u00e7\u00e3o de contribuintes \u00e9 aprovado na Alese"}]},{"@type":"WebSite","@id":"https:\/\/ocoerente.com.br\/se\/#website","url":"https:\/\/ocoerente.com.br\/se\/","name":"O Coerente","description":"","publisher":{"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ocoerente.com.br\/se\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/ocoerente.com.br\/se\/#\/schema\/person\/cc6bfd9fbca465e23543b0c963d8d037","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","url":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","contentUrl":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png","width":50,"height":50,"caption":"Reda\u00e7\u00e3o"},"logo":{"@id":"https:\/\/ocoerente.com.br\/se\/wp-content\/uploads\/2020\/01\/ocoerente-1.png"},"url":"https:\/\/ocoerente.com.br\/se\/author\/vasticlsales\/"}]}},"_links":{"self":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/11545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/comments?post=11545"}],"version-history":[{"count":1,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/11545\/revisions"}],"predecessor-version":[{"id":11547,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/posts\/11545\/revisions\/11547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media\/11546"}],"wp:attachment":[{"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/media?parent=11545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/categories?post=11545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ocoerente.com.br\/se\/wp-json\/wp\/v2\/tags?post=11545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}